{"id":176,"date":"2009-06-06T07:03:31","date_gmt":"2009-06-06T12:03:31","guid":{"rendered":"http:\/\/blogue.uqam.ca\/consommation\/?p=176"},"modified":"2009-06-06T07:03:31","modified_gmt":"2009-06-06T12:03:31","slug":"les-technologies-de-guerre-introduction","status":"publish","type":"post","link":"https:\/\/blogue.uqam.ca\/consommation\/2009\/06\/06\/les-technologies-de-guerre-introduction\/","title":{"rendered":"Les technologies de guerre : introduction"},"content":{"rendered":"<p>Nous c\u00e9l\u00e9brons aujourd\u2019hui le <a href=\"http:\/\/www.dday-overlord.com\/commemorations_normandie_2009.htm\">65e anniversaire du d\u00e9barquement de Normandie<\/a> (Jour J) qui marque le d\u00e9but de la reconqu\u00eate de l&rsquo;Europe par les pays alli\u00e9s. Je crois qu&rsquo;il est appropri\u00e9, voire indispensable, d&rsquo;avoir une pens\u00e9e pour les milliers de femmes et d&rsquo;hommes qui ont donn\u00e9 leur vie repousser l\u2019envahisseur et de reconqu\u00e9rir les territoires occup\u00e9s. C&rsquo;est \u00e9galement pour moi l&rsquo;opportunit\u00e9 d&rsquo;entreprendre une s\u00e9rie de chroniques portant sur les technologies de guerre. Commen\u00e7ons par un peu d&rsquo;histoire.<\/p>\n<p>La fin des ann\u00e9es trente voit se r\u00e9sorber tranquillement la Grande d\u00e9pression qui a s\u00e9vi pendant toute une d\u00e9cennie. Les d\u00e9mocraties occidentales se concentrent sur les moyens \u00e0 prendre pour faire red\u00e9marrer leurs \u00e9conomies respectives; elles visent donc avant tout \u00e0 maintenir la paix en Europe et, pour ce faire, font preuve de tol\u00e9rance envers Hitler. L\u2019annexion de l\u2019Autriche r\u00e9sultant de l\u2019<em>Anschluss<\/em> de 1938 est un premier pas de l\u2019Allemagne pour \u00e9largir les fronti\u00e8res impos\u00e9es par le trait\u00e9 de Versailles qui a mis fin \u00e0 la Premi\u00e8re Guerre mondiale. Lors d\u2019une conf\u00e9rence \u00e0 Munich en septembre 1938, dans un effort d\u2019apaisement du F\u00fchrer allemand, les dirigeants fran\u00e7ais et anglais ent\u00e9rinent les accords de Munich qui conc\u00e8dent \u00e0 l\u2019Allemagne l\u2019annexion des monts Sud\u00e8tes sur le territoire de la Tch\u00e9coslovaquie. Le 1er septembre 1939, l\u2019Allemagne envahi la Pologne; deux jours plus tard, le Royaume-Uni, la France et d\u2019autres pays lui d\u00e9clarent la guerre. Elle durera six longues ann\u00e9es et s\u2019\u00e9tendra \u00e0 plusieurs continents et oc\u00e9ans.<\/p>\n<p>Comme tous les conflits, la Seconde Guerre mondiale a acc\u00e9l\u00e9r\u00e9 le d\u00e9veloppement technologique; les p\u00e9riodes de crise sont favorables aux nouvelles inventions, en partie parce que l\u2019aiguillon de l\u2019urgence favorise la cr\u00e9ativit\u00e9 et aussi parce que les cr\u00e9dits accord\u00e9s au d\u00e9veloppement technologique par les gouvernements sont alors, sinon illimit\u00e9s, du moins fortement augment\u00e9s. Je ne vais pas tenter de faire une \u00e9num\u00e9ration exhaustive de toutes les technologies de guerre. Pour ces chroniques, je retiens l\u2019aviation et l\u2019espace.<\/p>\n<p>Je commencerai la semaine prochaine avec la p\u00e9riode du <a href=\"http:\/\/www.2worldwar2.com\/blitzkrieg.htm\"><em>Blitzkrieg<\/em><\/a>, le concept de guerre \u00e9clair qui a permis \u00e0 Hitler d\u2019envahir toute l\u2019Europe, puis l\u2019Afrique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous c\u00e9l\u00e9brons aujourd\u2019hui le 65e anniversaire du d\u00e9barquement de Normandie (Jour J) qui marque le d\u00e9but de la reconqu\u00eate de l&rsquo;Europe par les pays alli\u00e9s. Je crois qu&rsquo;il est appropri\u00e9, voire indispensable, d&rsquo;avoir une pens\u00e9e pour les milliers de femmes et d&rsquo;hommes qui ont donn\u00e9 leur vie repousser l\u2019envahisseur et de reconqu\u00e9rir les territoires occup\u00e9s. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogue.uqam.ca\/consommation\/wp-json\/wp\/v2\/posts\/176"}],"collection":[{"href":"https:\/\/blogue.uqam.ca\/consommation\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogue.uqam.ca\/consommation\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogue.uqam.ca\/consommation\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogue.uqam.ca\/consommation\/wp-json\/wp\/v2\/comments?post=176"}],"version-history":[{"count":0,"href":"https:\/\/blogue.uqam.ca\/consommation\/wp-json\/wp\/v2\/posts\/176\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogue.uqam.ca\/consommation\/wp-json\/wp\/v2\/media?parent=176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogue.uqam.ca\/consommation\/wp-json\/wp\/v2\/categories?post=176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogue.uqam.ca\/consommation\/wp-json\/wp\/v2\/tags?post=176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}